{"id":9224,"date":"2024-10-18T14:04:13","date_gmt":"2024-10-18T14:04:13","guid":{"rendered":"https:\/\/claus-von-benz.com\/?post_type=property&#038;p=9224"},"modified":"2025-08-26T14:13:07","modified_gmt":"2025-08-26T14:13:07","slug":"mancor-de-la-vall-centro-de-la-isla-casa-de-pueblo-mallorquina-bellamente-reformada-con-vistas-a-la-montana-y-terraza","status":"publish","type":"property","link":"https:\/\/claus-von-benz.com\/es\/inmobiliaria-mallorca\/mancor-de-la-vall-centro-de-la-isla-casa-de-pueblo-mallorquina-bellamente-reformada-con-vistas-a-la-montana-y-terraza\/","title":{"rendered":"Mancor de la Vall (centro de la isla) - Preciosa casa de pueblo mallorquina reformada con vistas a la monta\u00f1a y terraza"},"content":{"rendered":"<p>En el coraz\u00f3n del pintoresco Mancor de la Vall, con impresionantes vistas a la sierra de Tramuntana, se encuentra esta hermosa casa de pueblo mallorquina con sus t\u00edpicas paredes de piedra y vigas de madera, que fue completamente renovada en 2023\/24.<br>\u00a0<br>La casa, construida en 1890 en dos niveles, fue dise\u00f1ada con un gusto exquisito y conserva los elementos armoniosos que caracterizan la arquitectura de anta\u00f1o. En la planta baja hay 2 habitaciones di\u00e1fanas, la cocina americana (con pasaplatos) y un cuarto de ba\u00f1o con ducha. Por supuesto, el futuro propietario tambi\u00e9n puede restaurar el dormitorio original de la zona de entrada - completamente mallorqu\u00edn - para poder ofrecer a los hu\u00e9spedes un lugar donde dormir.<br>\u00a0<br>La planta superior de 51 m\u00b2 se divide en un dormitorio muy amplio con cuarto de ba\u00f1o en suite con ducha y una sala di\u00e1fana con estufa de le\u00f1a, que ofrece acceso directo a una terraza de 24 m\u00b2 con vistas ininterrumpidas hacia las monta\u00f1as como m\u00e1gico tel\u00f3n de fondo.<br>\u00a0<br>Las puertas, ventanas y contraventanas de madera, as\u00ed como las baldosas de cer\u00e1mica, a\u00f1aden encanto a su nuevo hogar. Hay preinstalaci\u00f3n de aire acondicionado.<br>\u00a0<br>Aqu\u00ed se respira mucha historia, sobre todo si se tiene en cuenta la atenci\u00f3n al detalle de estas calles tan cuidadas, decoradas con macetas y plantas que deleitan la vista. \u00a1Una aut\u00e9ntica joya!<br>\u00a0<br>La casa es adecuada para dos personas, pero ofrece la posibilidad f\u00e1cil de un segundo dormitorio en la planta baja (se puede discutir con los propietarios). Para concertar una visita, p\u00f3ngase en contacto con nosotros y estaremos encantados de mostrarle este lugar lleno de encanto.<br>\u00a0<br><strong>PROPIEDADES<\/strong><br>- Parcela: 69 m\u00b2<br>- Superficie habitable: 69 + 51 m\u00b2 = 120 m\u00b2<br>- Superficie construida: 146 m\u00b2<br>- Terraza: 18 m\u00b2<br>- A\u00f1o de construcci\u00f3n: 1890\u00a0<br>- Estado: renovado<br>- Estufa de le\u00f1a<br>- Preinstalaci\u00f3n de aire acondicionado fr\u00edo\/calor<br>- Tipo de suelo: Baldosas de cer\u00e1mica<br>- Certificado energ\u00e9tico: Clase E<br>- C\u00e9dula de habitabilidad: v\u00e1lida<br>- Vistas: a la carretera y a las monta\u00f1as<br>- Impuesto anual sobre bienes inmuebles y residuos: 280 EUR y 150 EUR<br>\u2028<br>SIN COMISIONES PARA EL COMPRADOR.<br>Si esta podr\u00eda ser la propiedad de sus sue\u00f1os, \u00a1SIMPLEMENTE LL\u00c1MENOS!<\/p>\n\n\n\n<p>Toda la informaci\u00f3n procede de los vendedores. Sujeto a alteraciones, salvo errores y omisiones.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>En el coraz\u00f3n del pintoresco Mancor de la Vall, con impresionantes vistas a la Sierra de Tramuntana, se encuentra esta hermosa casa de pueblo mallorquina con sus t\u00edpicas paredes de piedra y vigas de madera, que fue completamente renovada en 2023\/24. Datada de 1890 y construida en dos niveles, la casa ha sido dise\u00f1ada con un gusto exquisito y conserva los elementos armoniosos que caracterizan la arquitectura [...]<\/p>","protected":false},"author":2,"featured_media":9250,"parent":0,"menu_order":0,"template":"","property_type":[150],"property_status":[],"property_feature":[126],"property_label":[148],"property_country":[65],"property_state":[66],"property_city":[210],"property_area":[116],"class_list":["post-9224","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-stadthaus-kaufen-mallorca","property_feature-kueche","property_label-verkauft","property_country-spanien","property_state-mallorca","property_city-mancor-de-la-vall","property_area-inselmitte"],"property_meta":{"_edit_lock":["1767289936:9"],"_thumbnail_id":["9250"],"_edit_last":["9"],"fave_property_price":["465000"],"fave_show_price_placeholder":["0"],"fave_property_size":["120"],"fave_property_land":["69"],"fave_property_year":["1890"],"fave_property_id":["CVB-2041"],"fave_property_map":["1"],"fave_property_map_address":["Mancor de la Vall, Raiguer, Illes Balears, 07312, Espa\u00f1a"],"fave_property_location":["39.7501386,2.8709873,15"],"houzez_geolocation_lat":["39.7501386"],"houzez_geolocation_long":["2.8709873"],"fave_property_map_street_view":["show"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_loggedintoview":["0"],"fave_agent_display_option":["agent_info"],"fave_agents":["158"],"fave_prop_homeslider":["no"],"fave_private_note":["Partner von Isabel"],"fave_energy_class":["E"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"additional_features":["a:1:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:7:\"Zustand\";s:29:\"fave_additional_feature_value\";s:7:\"Saniert\";}}"],"_uf_disable_surveys":[""],"_seopress_redirections_type":["301"],"_seopress_redirections_logged_status":["both"],"_seopress_video":["a:1:{i:0;a:8:{s:3:\"url\";s:0:\"\";s:5:\"title\";s:0:\"\";s:4:\"desc\";s:0:\"\";s:9:\"thumbnail\";s:0:\"\";s:8:\"duration\";s:0:\"\";s:6:\"rating\";s:0:\"\";s:10:\"view_count\";s:0:\"\";s:3:\"tag\";s:0:\"\";}}"],"_seopress_analysis_target_kw":[""],"om_disable_all_campaigns":[""],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"houzez_total_property_views":["555"],"houzez_views_by_date":["a:61:{s:10:\"03-09-2026\";i:3;s:10:\"03-10-2026\";i:7;s:10:\"03-11-2026\";i:6;s:10:\"03-12-2026\";i:3;s:10:\"03-13-2026\";i:6;s:10:\"03-14-2026\";i:3;s:10:\"03-16-2026\";i:1;s:10:\"03-17-2026\";i:4;s:10:\"03-18-2026\";i:7;s:10:\"03-19-2026\";i:13;s:10:\"03-20-2026\";i:8;s:10:\"03-21-2026\";i:3;s:10:\"03-22-2026\";i:6;s:10:\"03-23-2026\";i:2;s:10:\"03-24-2026\";i:7;s:10:\"03-25-2026\";i:13;s:10:\"03-26-2026\";i:8;s:10:\"03-27-2026\";i:1;s:10:\"03-28-2026\";i:1;s:10:\"03-29-2026\";i:7;s:10:\"03-31-2026\";i:3;s:10:\"04-01-2026\";i:2;s:10:\"04-02-2026\";i:8;s:10:\"04-03-2026\";i:3;s:10:\"04-04-2026\";i:4;s:10:\"04-05-2026\";i:2;s:10:\"04-06-2026\";i:4;s:10:\"04-08-2026\";i:1;s:10:\"04-09-2026\";i:2;s:10:\"04-11-2026\";i:3;s:10:\"04-12-2026\";i:3;s:10:\"04-13-2026\";i:1;s:10:\"04-14-2026\";i:5;s:10:\"04-15-2026\";i:1;s:10:\"04-16-2026\";i:1;s:10:\"04-17-2026\";i:9;s:10:\"04-18-2026\";i:2;s:10:\"04-19-2026\";i:9;s:10:\"04-20-2026\";i:4;s:10:\"04-21-2026\";i:4;s:10:\"04-22-2026\";i:4;s:10:\"04-23-2026\";i:3;s:10:\"04-24-2026\";i:4;s:10:\"04-25-2026\";i:6;s:10:\"04-26-2026\";i:4;s:10:\"04-27-2026\";i:5;s:10:\"04-28-2026\";i:7;s:10:\"04-30-2026\";i:6;s:10:\"05-01-2026\";i:7;s:10:\"05-02-2026\";i:4;s:10:\"05-03-2026\";i:2;s:10:\"05-04-2026\";i:7;s:10:\"05-05-2026\";i:1;s:10:\"05-06-2026\";i:2;s:10:\"05-07-2026\";i:5;s:10:\"05-08-2026\";i:6;s:10:\"05-09-2026\";i:4;s:10:\"05-10-2026\";i:2;s:10:\"05-11-2026\";i:5;s:10:\"05-12-2026\";i:1;s:10:\"05-13-2026\";i:5;}"],"houzez_recently_viewed":["2026-05-13 17:01:58"],"_trp_automatically_translated_slug_es_ES":["mancor-de-la-vall-centro-de-la-isla-casa-de-pueblo-mallorquina-bellamente-reformada-con-vistas-a-la-montana-y-terraza"],"_trp_automatically_translated_slug_en_US":["mancor-de-la-vall-center-of-the-island-beautifully-renovated-mallorcan-village-house-with-mountain-view-and-terrace"],"fave_property_bedrooms":["2"],"fave_property_bathrooms":["2"],"fave_property_images":["9246","9247","9231","9249","9248","9238","9233","9245","9244","9237","9243","9232","9234","9236","9235","9228","9229","9230","9241","9242","9240","9239"],"_elementor_page_assets":["a:0:{}"]},"_links":{"self":[{"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/properties\/9224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":3,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/properties\/9224\/revisions"}],"predecessor-version":[{"id":12603,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/properties\/9224\/revisions\/12603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/media\/9250"}],"wp:attachment":[{"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/media?parent=9224"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/property_type?post=9224"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/property_status?post=9224"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/property_feature?post=9224"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/property_label?post=9224"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/property_country?post=9224"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/property_state?post=9224"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/property_city?post=9224"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/claus-von-benz.com\/es\/wp-json\/wp\/v2\/property_area?post=9224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}